{"id":1281,"date":"2024-05-07T17:28:16","date_gmt":"2024-05-07T17:28:16","guid":{"rendered":"https:\/\/gsantana2005.net\/?p=1281"},"modified":"2024-05-07T17:31:41","modified_gmt":"2024-05-07T17:31:41","slug":"transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel","status":"publish","type":"post","link":"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/","title":{"rendered":"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel"},"content":{"rendered":"\n<p>Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel \u00e9 um artigo que representa uma esperan\u00e7a para o tratamento de \u00e1guas residuais. Ent\u00e3o, em um mundo onde a sustentabilidade se torna cada vez mais importante pesquisadores est\u00e3o abrindo caminhos inovadores para transformar problemas ambientais em solu\u00e7\u00f5es valiosas. Uma dessas inova\u00e7\u00f5es promissoras \u00e9 o m\u00e9todo rec\u00e9m-proposto de transformar contaminantes de \u00e1guas residuais em produtos qu\u00edmicos valiosos. Assim, ela utiliza nada menos que a energia do sol. Este avan\u00e7o, publicado na revista <em>Nature Sustainability<\/em> em outubro, \u00e9 liderado pelos professores GAO Xiang, do Instituto de Tecnologia Avan\u00e7ada de Shenzhen (SIAT) da Academia Chinesa de Ci\u00eancias, e LU Lu, do Instituto de Tecnologia de Harbin.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>A Inova\u00e7\u00e3o dos Bioh\u00edbridos Semicondutores<\/strong><\/h3>\n\n\n\n<p> A princ\u00edpio, a fabrica\u00e7\u00e3o qu\u00edmica convencional depende de processos que consomem muita energia. No entanto, os bioh\u00edbridos semicondutores, que combinam materiais eficientes na capta\u00e7\u00e3o de luz e c\u00e9lulas vivas, possibilitam uma possibilidade empolgante. Dessa forma, esses bioh\u00edbridos s\u00e3o projetados para usar energia solar para produzir produtos qu\u00edmicos, representando um m\u00e9todo mais sustent\u00e1vel e circular de fabrica\u00e7\u00e3o qu\u00edmica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Desafios e Solu\u00e7\u00f5es<\/strong><\/h3>\n\n\n\n<p>O principal desafio \u00e9 encontrar uma maneira economicamente vi\u00e1vel e ambientalmente amig\u00e1vel de escalar essa tecnologia. Os pesquisadores se propuseram a converter poluentes de \u00e1guas residuais em bioh\u00edbridos semicondutores diretamente no ambiente das \u00e1guas residuais, utilizando carbono org\u00e2nico, metais pesados e compostos de sulfato presentes como mat\u00e9rias-primas.<\/p>\n\n\n\n<p>No entanto, a composi\u00e7\u00e3o vari\u00e1vel e muitas vezes t\u00f3xica das \u00e1guas residuais industriais representa um desafio significativo. Para superar isso, os pesquisadores selecionaram uma bact\u00e9ria marinha de crescimento r\u00e1pido, <em>Vibrio natriegens<\/em>, conhecida por sua toler\u00e2ncia a altas concentra\u00e7\u00f5es de sal e capacidade de utilizar diversas fontes de carbono. Eles introduziram um caminho de redu\u00e7\u00e3o de sulfato aer\u00f3bico em <em>V. natriegens<\/em> e treinaram a cepa para produzir bioh\u00edbridos semicondutores diretamente dessas \u00e1guas residuais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Produ\u00e7\u00e3o de 2,3-Butanodiol<\/strong><\/h3>\n\n\n\n<p>O principal produto qu\u00edmico alvo para produ\u00e7\u00e3o foi o 2,3-butanodiol (BDO), um valioso produto qu\u00edmico comercial. Atrav\u00e9s da engenharia de <em>V. natriegens<\/em>, os pesquisadores conseguiram gerar sulfeto de hidrog\u00eanio, facilitando a produ\u00e7\u00e3o de nanopart\u00edculas de sulfeto de c\u00e1dmio (CdS) que absorvem luz eficientemente. Essas nanopart\u00edculas permitiram a cria\u00e7\u00e3o in situ de bioh\u00edbridos semicondutores, possibilitando que bact\u00e9rias n\u00e3o fotossint\u00e9ticas utilizassem luz.<\/p>\n\n\n\n<p>Os resultados mostraram que esses bioh\u00edbridos ativados pela luz solar exibiram uma produ\u00e7\u00e3o de BDO significativamente aprimorada, superando os rendimentos alcan\u00e7\u00e1veis apenas por c\u00e9lulas bacterianas. Al\u00e9m disso, o processo mostrou ser escal\u00e1vel, alcan\u00e7ando a produ\u00e7\u00e3o de BDO movida a energia solar em uma escala substancial de 5 litros usando \u00e1guas residuais reais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Impacto Ambiental e Econ\u00f4mico<\/strong><\/h3>\n\n\n\n<p>A avalia\u00e7\u00e3o do ciclo de vida indica que este m\u00e9todo bioh\u00edbrido oferece ganhos substanciais de sustentabilidade em compara\u00e7\u00e3o com as rotas de produ\u00e7\u00e3o convencionais de 2,3-butanodiol. \u201cA plataforma bioh\u00edbrida n\u00e3o apenas possui uma pegada de carbono menor, mas tamb\u00e9m reduz os custos dos produtos, levando a um impacto ambiental geral menor em compara\u00e7\u00e3o com os m\u00e9todos de produ\u00e7\u00e3o de BDO baseados em fermenta\u00e7\u00e3o bacteriana tradicional e combust\u00edveis f\u00f3sseis\u201d, explicou o Prof. GAO.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Rumo a um Futuro Sustent\u00e1vel<\/strong><\/h3>\n\n\n\n<p>Este trabalho representa um passo significativo em dire\u00e7\u00e3o \u00e0 biomanufatura movida a energia solar e \u00e0 convers\u00e3o de res\u00edduos em riqueza, pavimentando o caminho para uma produ\u00e7\u00e3o mais limpa e uma economia circular. Ao transformar \u00e1guas residuais, um problema ambiental, em produtos qu\u00edmicos valiosos de maneira sustent\u00e1vel, os pesquisadores est\u00e3o n\u00e3o apenas enfrentando desafios ambientais, mas tamb\u00e9m abrindo novas avenidas para a inova\u00e7\u00e3o na fabrica\u00e7\u00e3o qu\u00edmica.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Fonte<\/h4>\n\n\n\n<p><a href=\"https:\/\/envirotecmagazine.com\/2024\/01\/12\/biohybrid-alchemy-transforming-wastewater-contaminants-into-chemicals\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Envirotec<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Convite especial para voc\u00ea<\/h3>\n\n\n\n<p>Ent\u00e3o, depois de Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel, acredito que voc\u00ea queira saber mais de nossa contribui\u00e7\u00e3o na \u00e1rea ambiental. N\u00e3o fique inibido entre em contato:\u00a0<a href=\"mailto:gsantana2005@gmail.com\">gsantana2005@gmail.com<\/a>\u00a0veja o nosso\u00a0<a href=\"https:\/\/www.instagram.com\/genilsonpereirasantana1\/\" rel=\"nofollow noopener\" target=\"_blank\">Instagram<\/a><\/p>\n\n\n\n<p>Al\u00e9m disso, j\u00e1 que voc\u00ea chegou at\u00e9 aqui descubra mais sobre n\u00f3s artigos abaixo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/gsantana2005.net\/index.php\/2023\/11\/30\/desbloqueando-o-valor-oculto-reciclando-o-pequeno-para-um-grande-impacto\/\" target=\"_blank\" rel=\"noreferrer noopener\">Desbloqueando o valor oculto: Reciclando o pequeno para um grande impacto<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/gsantana2005.net\/index.php\/2023\/11\/29\/reduza-a-pegada-de-carbono-digital-da-sua-empresa-rumo-a-um-futuro-sustentavel\/\" target=\"_blank\" rel=\"noreferrer noopener\">Reduza a Pegada de Carbono Digital da sua Empresa: Rumo a um Futuro Sustent\u00e1vel<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/gsantana2005.net\/index.php\/2023\/11\/28\/navegando-na-controversia-da-acao-climatica-global-da-cop28-de-dubai\/\" target=\"_blank\" rel=\"noreferrer noopener\">Navegando na controv\u00e9rsia da A\u00e7\u00e3o Clim\u00e1tica Global da COP28 de Dubai<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/gsantana2005.net\/index.php\/2023\/11\/28\/rascunho-automaticodespedindo-se-dos-plasticos-descartaveis-o-futuro-sustentavel-das-embalagens-de-celulose\/\">Despedindo-se dos Pl\u00e1sticos Descart\u00e1veis: O Futuro Sustent\u00e1vel das Embalagens de Celulose!<\/a><\/li>\n<\/ul>\n\n\n\n<p>Ent\u00e3o, conhe\u00e7a tamb\u00e9m nossos cursos sobre&nbsp;<a href=\"https:\/\/gsantana2005.net\/index.php\/2023\/07\/21\/gestao-de-residuos\/\">Gest\u00e3o de res\u00edduos<\/a>&nbsp;e&nbsp;<a href=\"https:\/\/gsantana2005.net\/index.php\/2023\/08\/08\/tratamento-de-efluentes\/\">Tratamento de efluentes<\/a>. Maiores informa\u00e7\u00f5es:&nbsp;<a href=\"mailto:gsantana2005@gmail.com\">gsantana2005@gmail.com<\/a>&nbsp;ou 92 991227158 (WhatsApp)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel \u00e9 um artigo que representa uma esperan\u00e7a para o tratamento de \u00e1guas residuais. Ent\u00e3o, em um mundo onde a sustentabilidade se torna cada vez mais importante pesquisadores est\u00e3o abrindo caminhos inovadores para transformar problemas ambientais em solu\u00e7\u00f5es valiosas. Uma dessas inova\u00e7\u00f5es promissoras \u00e9 o m\u00e9todo rec\u00e9m-proposto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1282,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[2,275,3],"tags":[1106,1100,1109,1103,1107,1101,1105,1102,1108,1099,1104],"class_list":["post-1281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente","category-conservacao-ambiental","category-genilson-pereira-santana","tag-3-butanodiol","tag-biohibridos-semicondutores-sustentaveis","tag-biomanufatura-solar-e-economia-circular","tag-inovacao-em-fabricacao-quimica-circular","tag-nanoparticulas-de-cds-em-biotecnologia","tag-producao-de-quimicos-com-energia-solar","tag-producao-sustentavel-de-2","tag-reciclagem-de-contaminantes-em-valor","tag-reducao-de-carbono-em-quimica-industrial","tag-transformacao-de-aguas-residuais","tag-vibrio-natriegens-e-tratamento-de-agua"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel - gsantana2005<\/title>\n<meta name=\"description\" content=\"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel \u00e9 um artigo que mostra para voc\u00ea essa novidade\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel - gsantana2005\" \/>\n<meta property=\"og:description\" content=\"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel \u00e9 um artigo que mostra para voc\u00ea essa novidade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/\" \/>\n<meta property=\"og:site_name\" content=\"gsantana2005\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-07T17:28:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-07T17:31:41+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/gsantana2005.net\/wp-content\/uploads\/2024\/05\/aguas-residuais.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gsantana2005\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"gsantana2005\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/\"},\"author\":{\"name\":\"gsantana2005\",\"@id\":\"https:\/\/gsantana2005.net\/#\/schema\/person\/78c90c6f49a46ef4c8e69bafec347cb7\"},\"headline\":\"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel\",\"datePublished\":\"2024-05-07T17:28:16+00:00\",\"dateModified\":\"2024-05-07T17:31:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/\"},\"wordCount\":809,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/gsantana2005.net\/#organization\"},\"image\":{\"@id\":\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gsantana2005.net\/wp-content\/uploads\/2024\/05\/aguas-residuais.jpg\",\"keywords\":[\"3-butanodiol\",\"bioh\u00edbridos semicondutores sustent\u00e1veis\",\"biomanufatura solar e economia circular\",\"inova\u00e7\u00e3o em fabrica\u00e7\u00e3o qu\u00edmica circular\",\"nanopart\u00edculas de CdS em biotecnologia\",\"produ\u00e7\u00e3o de qu\u00edmicos com energia solar\",\"produ\u00e7\u00e3o sustent\u00e1vel de 2\",\"reciclagem de contaminantes em valor\",\"redu\u00e7\u00e3o de carbono em qu\u00edmica industrial\",\"transforma\u00e7\u00e3o de \u00e1guas residuais\",\"Vibrio natriegens e tratamento de \u00e1gua\"],\"articleSection\":[\"Ambiente\",\"Conserva\u00e7\u00e3o Ambiental\",\"Dr Genilson Santana\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/\",\"url\":\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/\",\"name\":\"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel - gsantana2005\",\"isPartOf\":{\"@id\":\"https:\/\/gsantana2005.net\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gsantana2005.net\/wp-content\/uploads\/2024\/05\/aguas-residuais.jpg\",\"datePublished\":\"2024-05-07T17:28:16+00:00\",\"dateModified\":\"2024-05-07T17:31:41+00:00\",\"description\":\"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel \u00e9 um artigo que mostra para voc\u00ea essa novidade\",\"breadcrumb\":{\"@id\":\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#primaryimage\",\"url\":\"https:\/\/gsantana2005.net\/wp-content\/uploads\/2024\/05\/aguas-residuais.jpg\",\"contentUrl\":\"https:\/\/gsantana2005.net\/wp-content\/uploads\/2024\/05\/aguas-residuais.jpg\",\"width\":1200,\"height\":800,\"caption\":\"\u00c1guas residuais\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/gsantana2005.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gsantana2005.net\/#website\",\"url\":\"https:\/\/gsantana2005.net\/\",\"name\":\"gsantana2005\",\"description\":\"Sejamos sustent\u00e1veis\",\"publisher\":{\"@id\":\"https:\/\/gsantana2005.net\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gsantana2005.net\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gsantana2005.net\/#organization\",\"name\":\"gsantana2005\",\"url\":\"https:\/\/gsantana2005.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/gsantana2005.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gsantana2005.net\/wp-content\/uploads\/2023\/06\/cropped-Gs-sem-fundo.jpg\",\"contentUrl\":\"https:\/\/gsantana2005.net\/wp-content\/uploads\/2023\/06\/cropped-Gs-sem-fundo.jpg\",\"width\":100,\"height\":100,\"caption\":\"gsantana2005\"},\"image\":{\"@id\":\"https:\/\/gsantana2005.net\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/gsantana2005.net\/#\/schema\/person\/78c90c6f49a46ef4c8e69bafec347cb7\",\"name\":\"gsantana2005\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/gsantana2005.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/db3aa311fa8063e1f4df6b2da249929f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/db3aa311fa8063e1f4df6b2da249929f?s=96&d=mm&r=g\",\"caption\":\"gsantana2005\"},\"sameAs\":[\"http:\/\/gsantana2005.net\"],\"url\":\"https:\/\/gsantana2005.net\/author\/gsantana2005\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel - gsantana2005","description":"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel \u00e9 um artigo que mostra para voc\u00ea essa novidade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/","og_locale":"pt_BR","og_type":"article","og_title":"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel - gsantana2005","og_description":"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel \u00e9 um artigo que mostra para voc\u00ea essa novidade","og_url":"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/","og_site_name":"gsantana2005","article_published_time":"2024-05-07T17:28:16+00:00","article_modified_time":"2024-05-07T17:31:41+00:00","og_image":[{"width":1200,"height":800,"url":"http:\/\/gsantana2005.net\/wp-content\/uploads\/2024\/05\/aguas-residuais.jpg","type":"image\/jpeg"}],"author":"gsantana2005","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"gsantana2005","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#article","isPartOf":{"@id":"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/"},"author":{"name":"gsantana2005","@id":"https:\/\/gsantana2005.net\/#\/schema\/person\/78c90c6f49a46ef4c8e69bafec347cb7"},"headline":"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel","datePublished":"2024-05-07T17:28:16+00:00","dateModified":"2024-05-07T17:31:41+00:00","mainEntityOfPage":{"@id":"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/"},"wordCount":809,"commentCount":0,"publisher":{"@id":"https:\/\/gsantana2005.net\/#organization"},"image":{"@id":"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#primaryimage"},"thumbnailUrl":"https:\/\/gsantana2005.net\/wp-content\/uploads\/2024\/05\/aguas-residuais.jpg","keywords":["3-butanodiol","bioh\u00edbridos semicondutores sustent\u00e1veis","biomanufatura solar e economia circular","inova\u00e7\u00e3o em fabrica\u00e7\u00e3o qu\u00edmica circular","nanopart\u00edculas de CdS em biotecnologia","produ\u00e7\u00e3o de qu\u00edmicos com energia solar","produ\u00e7\u00e3o sustent\u00e1vel de 2","reciclagem de contaminantes em valor","redu\u00e7\u00e3o de carbono em qu\u00edmica industrial","transforma\u00e7\u00e3o de \u00e1guas residuais","Vibrio natriegens e tratamento de \u00e1gua"],"articleSection":["Ambiente","Conserva\u00e7\u00e3o Ambiental","Dr Genilson Santana"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/","url":"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/","name":"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel - gsantana2005","isPartOf":{"@id":"https:\/\/gsantana2005.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#primaryimage"},"image":{"@id":"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#primaryimage"},"thumbnailUrl":"https:\/\/gsantana2005.net\/wp-content\/uploads\/2024\/05\/aguas-residuais.jpg","datePublished":"2024-05-07T17:28:16+00:00","dateModified":"2024-05-07T17:31:41+00:00","description":"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel \u00e9 um artigo que mostra para voc\u00ea essa novidade","breadcrumb":{"@id":"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#primaryimage","url":"https:\/\/gsantana2005.net\/wp-content\/uploads\/2024\/05\/aguas-residuais.jpg","contentUrl":"https:\/\/gsantana2005.net\/wp-content\/uploads\/2024\/05\/aguas-residuais.jpg","width":1200,"height":800,"caption":"\u00c1guas residuais"},{"@type":"BreadcrumbList","@id":"https:\/\/gsantana2005.net\/index.php\/2024\/05\/07\/transformando-aguas-residuais-em-quimicos-valiosos-uma-revolucao-sustentavel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gsantana2005.net\/"},{"@type":"ListItem","position":2,"name":"Transformando \u00c1guas Residuais em Qu\u00edmicos Valiosos: Uma Revolu\u00e7\u00e3o Sustent\u00e1vel"}]},{"@type":"WebSite","@id":"https:\/\/gsantana2005.net\/#website","url":"https:\/\/gsantana2005.net\/","name":"gsantana2005","description":"Sejamos sustent\u00e1veis","publisher":{"@id":"https:\/\/gsantana2005.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gsantana2005.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/gsantana2005.net\/#organization","name":"gsantana2005","url":"https:\/\/gsantana2005.net\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gsantana2005.net\/#\/schema\/logo\/image\/","url":"https:\/\/gsantana2005.net\/wp-content\/uploads\/2023\/06\/cropped-Gs-sem-fundo.jpg","contentUrl":"https:\/\/gsantana2005.net\/wp-content\/uploads\/2023\/06\/cropped-Gs-sem-fundo.jpg","width":100,"height":100,"caption":"gsantana2005"},"image":{"@id":"https:\/\/gsantana2005.net\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/gsantana2005.net\/#\/schema\/person\/78c90c6f49a46ef4c8e69bafec347cb7","name":"gsantana2005","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gsantana2005.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/db3aa311fa8063e1f4df6b2da249929f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db3aa311fa8063e1f4df6b2da249929f?s=96&d=mm&r=g","caption":"gsantana2005"},"sameAs":["http:\/\/gsantana2005.net"],"url":"https:\/\/gsantana2005.net\/author\/gsantana2005\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/gsantana2005.net\/index.php\/wp-json\/wp\/v2\/posts\/1281"}],"collection":[{"href":"https:\/\/gsantana2005.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gsantana2005.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gsantana2005.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gsantana2005.net\/index.php\/wp-json\/wp\/v2\/comments?post=1281"}],"version-history":[{"count":2,"href":"https:\/\/gsantana2005.net\/index.php\/wp-json\/wp\/v2\/posts\/1281\/revisions"}],"predecessor-version":[{"id":1285,"href":"https:\/\/gsantana2005.net\/index.php\/wp-json\/wp\/v2\/posts\/1281\/revisions\/1285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gsantana2005.net\/index.php\/wp-json\/wp\/v2\/media\/1282"}],"wp:attachment":[{"href":"https:\/\/gsantana2005.net\/index.php\/wp-json\/wp\/v2\/media?parent=1281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gsantana2005.net\/index.php\/wp-json\/wp\/v2\/categories?post=1281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gsantana2005.net\/index.php\/wp-json\/wp\/v2\/tags?post=1281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}